{"id":3,"date":"2024-05-13T22:21:27","date_gmt":"2024-05-13T20:21:27","guid":{"rendered":"https:\/\/graficointl.com\/prepanama\/?page_id=3"},"modified":"2024-05-28T19:24:01","modified_gmt":"2024-05-28T17:24:01","slug":"politica-privacidad","status":"publish","type":"page","link":"https:\/\/haciendalaperezosa.com\/en\/politica-privacidad\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\">\n\t\t\t\t<div class=\"elementor-element elementor-element-583b74d e-flex e-con-boxed e-con e-parent\" data-id=\"583b74d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4acd4c22 elementor-widget elementor-widget-text-editor\" data-id=\"4acd4c22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<h1 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>Pol\u00edticas de Privacidad<\/strong><\/span><\/h1>\n<p class=\"wp-block-paragraph\">Esta Pol\u00edtica de Privacidad rige la manera en la que La Perezosa recopila, utiliza, mantiene y divulga informaci\u00f3n recopilada de los usuarios.\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Uso de la informaci\u00f3n personal. La informaci\u00f3n personal que recopilamos se utiliza exclusivamente para el contacto con nuestros clientes que aceptan darnos esta informaci\u00f3n.\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n utilizamos esta informaci\u00f3n para fines estad\u00edsticos internos y para mejorar nuestros servicios.<\/p>\n\n<p class=\"wp-block-paragraph\">No compartimos su informaci\u00f3n personal con terceros sin su consentimiento expl\u00edcito, excepto cuando sea necesario para cumplir con la ley o proteger nuestros derechos.<\/p>\n\n<p class=\"wp-block-paragraph\">Comunicaciones por correo electr\u00f3nico. Solo enviamos correos electr\u00f3nicos a aquellos usuarios que han aceptado recibir comunicaciones por correo electr\u00f3nico de nuestra empresa. Nuestros correos electr\u00f3nicos incluyen informaci\u00f3n sobre nuestros proyectos y servicios, as\u00ed como otras noticias y actualizaciones que consideramos relevantes para nuestros usuarios.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Informaci\u00f3n de identificaci\u00f3n personal<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Podemos recopilar informaci\u00f3n de identificaci\u00f3n personal de los visitantes, incluidas, entre otras, cuando los visitantes se inscriben a La Perezosa, se suscriben a un bolet\u00edn informativo y en relaci\u00f3n con otras actividades, servicios, funciones, o recursos que ponemos a disposici\u00f3n en La Perezosa. Los visitantes pueden visitar La Perezosa de forma an\u00f3nima. Recopilaremos informaci\u00f3n de identificaci\u00f3n personal de los visitantes solo si nos env\u00edan voluntariamente dicha informaci\u00f3n. Los visitantes pueden negarse a proporcionar informaci\u00f3n de identificaci\u00f3n personal, pero hacerlo puede impedirles participar en ciertas actividades relacionadas con La Perezosa.<\/p>\n\n<p class=\"wp-block-paragraph\">C\u00f3mo utilizamos la informaci\u00f3n recopilada.<\/p>\n\n<p class=\"wp-block-paragraph\">La Perezosa puede recopilar y utilizar la informaci\u00f3n de identificaci\u00f3n personal de los visitantes para los siguientes prop\u00f3sitos:<\/p>\n\n<p class=\"wp-block-paragraph\">Mejorar el servicio al cliente.<br \/>La informaci\u00f3n que usted proporciona nos ayuda a responder a sus solicitudes de servicio al cliente y necesidades de soporte de manera m\u00e1s eficiente.<br \/>Para personalizar la experiencia del usuario.<br \/>Podemos utilizar informaci\u00f3n en conjunto para comprender c\u00f3mo nuestros visitantes como grupo utilizan los servicios y recursos proporcionados en La Perezosa.<br \/>Para enviar correos electr\u00f3nicos peri\u00f3dicos.<br \/>Podemos utilizar las direcciones de correo electr\u00f3nico de La Perezosa para enviarles informaci\u00f3n y actualizaciones relacionadas con su pedido. Las direcciones de correo electr\u00f3nico de los visitantes tambi\u00e9n se pueden utilizar para responder a consultas, preguntas u otras solicitudes de los visitantes.<br \/>Compartir su informaci\u00f3n personal<\/p>\n\n<p class=\"wp-block-paragraph\">No vendemos, intercambiamos ni alquilamos informaci\u00f3n de identificaci\u00f3n personal de los estudiantes a otros.<\/p>\n\n<p class=\"wp-block-paragraph\">Sitios web de terceros<\/p>\n\n<p class=\"wp-block-paragraph\">Los estudiantes pueden encontrar publicidad u otro contenido en La Perezosa que enlace a los sitios web y servicios de nuestros socios, proveedores, anunciantes, patrocinadores, licenciantes y otros terceros. No controlamos el contenido o los enlaces que aparecen en estos sitios web y no somos responsables de las pr\u00e1cticas empleadas por los sitios web vinculados hacia o desde La Perezosa. Adem\u00e1s, estos sitios web o servicios, incluido su contenido y enlaces, pueden cambiar constantemente. Estos sitios web y servicios pueden tener sus propias pol\u00edticas de privacidad y pol\u00edticas de servicio al cliente. La navegaci\u00f3n y la interacci\u00f3n en cualquier otro sitio web, incluidos los sitios web que tienen un enlace a La Perezosa, est\u00e1n sujetas a los t\u00e9rminos y pol\u00edticas propios de ese sitio web.<\/p>\n\n<p class=\"wp-block-paragraph\">Cambios a esta Pol\u00edtica de Privacidad<\/p>\n\n<p class=\"wp-block-paragraph\">La Perezosa tiene la discreci\u00f3n de actualizar esta Pol\u00edtica de Privacidad en cualquier momento. Alentamos a los visitantes a consultar con frecuencia esta p\u00e1gina para detectar cualquier cambio. Usted reconoce y acepta que es su responsabilidad revisar esta Pol\u00edtica de Privacidad peri\u00f3dicamente y estar al tanto de las modificaciones.<\/p>\n\n<p class=\"wp-block-paragraph\">Su aceptaci\u00f3n de estos t\u00e9rminos<\/p>\n\n<p class=\"wp-block-paragraph\">Al suscribirse a La Perezosa, usted manifiesta su aceptaci\u00f3n de esta Pol\u00edtica de Privacidad. Su inscripci\u00f3n continua en La Perezosa despu\u00e9s de la publicaci\u00f3n de cambios a esta Pol\u00edtica de Privacidad se considerar\u00e1 su aceptaci\u00f3n de dichos cambios.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edticas de Privacidad Esta Pol\u00edtica de Privacidad rige la manera en la que La Perezosa recopila, utiliza, mantiene y divulga informaci\u00f3n recopilada de los usuarios.\u00a0 Uso de la informaci\u00f3n personal. La informaci\u00f3n personal que recopilamos se utiliza exclusivamente para el contacto con nuestros clientes que aceptan darnos esta informaci\u00f3n.\u00a0 Tambi\u00e9n utilizamos esta informaci\u00f3n para fines [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":7,"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":347,"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/347"}],"wp:attachment":[{"href":"https:\/\/haciendalaperezosa.com\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}